{"id":3839,"date":"2026-05-23T07:57:31","date_gmt":"2026-05-23T07:57:31","guid":{"rendered":"https:\/\/manufactorhinge.com\/?page_id=3839"},"modified":"2026-05-23T08:39:58","modified_gmt":"2026-05-23T08:39:58","slug":"panel-weight-calculator","status":"publish","type":"page","link":"https:\/\/manufactorhinge.com\/it\/panel-weight-calculator\/","title":{"rendered":"Calcolatore del peso del pannello"},"content":{"rendered":"<!-- Panel Weight Calculator for Torque Hinge Selection -->\n<section class=\"hsp-panel-weight-tool\">\n  <style>\n    .hsp-panel-weight-tool {\n      --hsp-blue: #0b4a8f;\n      --hsp-blue-soft: #eaf4ff;\n      --hsp-green: #0f7a63;\n      --hsp-green-soft: #e9f8f3;\n      --hsp-border: #d7e2ef;\n      --hsp-text: #1f2933;\n      --hsp-muted: #5f6b7a;\n      --hsp-bg: #f8fafc;\n      font-family: inherit;\n      color: var(--hsp-text);\n      background: #fff;\n      border: 1px solid var(--hsp-border);\n      border-radius: 18px;\n      padding: 28px;\n      margin: 30px 0;\n      box-shadow: 0 10px 30px rgba(15, 23, 42, 0.06);\n    }\n\n    .hsp-panel-weight-tool * {\n      box-sizing: border-box;\n    }\n\n    .hsp-tool-header {\n      max-width: 900px;\n      margin-bottom: 26px;\n    }\n\n    .hsp-tool-kicker {\n      display: inline-block;\n      font-size: 13px;\n      font-weight: 700;\n      color: var(--hsp-blue);\n      background: var(--hsp-blue-soft);\n      padding: 6px 12px;\n      border-radius: 999px;\n      margin-bottom: 12px;\n    }\n\n    .hsp-tool-header h2 {\n      font-size: clamp(26px, 4vw, 42px);\n      line-height: 1.15;\n      margin: 0 0 12px;\n      color: #0f2f57;\n      letter-spacing: -0.03em;\n    }\n\n    .hsp-tool-header p {\n      font-size: 16px;\n      line-height: 1.7;\n      color: var(--hsp-muted);\n      margin: 0;\n    }\n\n    .hsp-tool-grid {\n      display: grid;\n      grid-template-columns: 1fr 1fr;\n      gap: 26px;\n      align-items: stretch;\n    }\n\n    .hsp-visual-card,\n    .hsp-calculator-card {\n      border: 1px solid var(--hsp-border);\n      border-radius: 16px;\n      background: var(--hsp-bg);\n      padding: 22px;\n    }\n\n    .hsp-visual-card h3,\n    .hsp-calculator-card h3 {\n      font-size: 20px;\n      margin: 0 0 14px;\n      color: #113b68;\n    }\n\n    .hsp-panel-diagram {\n      position: relative;\n      min-height: 620px;\n      background: #f8fafc;\n      border: 1px dashed #c7d5e5;\n      border-radius: 14px;\n      padding: 8px;\n      overflow: hidden;\n    }\n\n    .hsp-door-svg {\n      width: 100%;\n      height: auto;\n      display: block;\n    }\n\n    .hsp-door-front {\n      fill: url(#hspDoorFront);\n    }\n\n    .hsp-door-side {\n      fill: url(#hspDoorSide);\n    }\n\n    .hsp-door-top {\n      fill: url(#hspDoorTop);\n    }\n\n    .hsp-dim-line,\n    .hsp-dim-tick {\n      stroke: #666;\n      stroke-width: 3;\n      fill: none;\n      transition: all 0.2s ease;\n    }\n\n    .hsp-arrow {\n      fill: #666;\n      transition: all 0.2s ease;\n    }\n\n    .hsp-dim-text {\n      fill: #333;\n      font-size: 32px;\n      font-weight: 500;\n      transition: all 0.2s ease;\n    }\n\n    .dim-width-text {\n      text-anchor: middle;\n    }\n\n    .active-dot {\n      fill: #0b4a8f;\n      opacity: 0;\n      transition: all 0.2s ease;\n    }\n\n    .hsp-panel-diagram.is-height-active .dim-height,\n    .hsp-panel-diagram.is-height-active .dim-height-text,\n    .hsp-panel-diagram.is-height-active .dim-height-arrow-top,\n    .hsp-panel-diagram.is-height-active .dim-height-arrow-bottom {\n      stroke: #0b4a8f;\n      fill: #0b4a8f;\n      stroke-width: 4;\n    }\n\n    .hsp-panel-diagram.is-width-active .dim-width,\n    .hsp-panel-diagram.is-width-active .dim-width-text,\n    .hsp-panel-diagram.is-width-active .dim-width-arrow-left,\n    .hsp-panel-diagram.is-width-active .dim-width-arrow-right {\n      stroke: #0b4a8f;\n      fill: #0b4a8f;\n      stroke-width: 4;\n    }\n\n    .hsp-panel-diagram.is-thickness-active .dim-thickness,\n    .hsp-panel-diagram.is-thickness-active .dim-thickness-text-1,\n    .hsp-panel-diagram.is-thickness-active .dim-thickness-text-2,\n    .hsp-panel-diagram.is-thickness-active .dim-thickness-arrow-left,\n    .hsp-panel-diagram.is-thickness-active .dim-thickness-arrow-right {\n      stroke: #0b4a8f;\n      fill: #0b4a8f;\n      stroke-width: 4;\n    }\n\n    .hsp-panel-diagram.is-height-active .active-height-dot,\n    .hsp-panel-diagram.is-width-active .active-width-dot,\n    .hsp-panel-diagram.is-thickness-active .active-thickness-dot {\n      opacity: 0.22;\n      r: 26;\n    }\n\n    .hsp-formula-box {\n      margin-top: 18px;\n      background: #fff;\n      border: 1px solid var(--hsp-border);\n      border-radius: 14px;\n      padding: 16px;\n      font-size: 15px;\n      line-height: 1.8;\n    }\n\n    .hsp-formula-box strong {\n      color: var(--hsp-blue);\n    }\n\n    .hsp-form-row {\n      margin-bottom: 16px;\n    }\n\n    .hsp-form-row label {\n      display: block;\n      font-size: 14px;\n      font-weight: 700;\n      color: #243447;\n      margin-bottom: 7px;\n    }\n\n    .hsp-form-row input,\n    .hsp-form-row select {\n      width: 100%;\n      height: 52px;\n      min-height: 52px;\n      border: 1px solid #c7d5e5;\n      border-radius: 10px;\n      padding: 0 14px;\n      font-size: 15px;\n      line-height: 52px;\n      background: #fff;\n      color: var(--hsp-text);\n      outline: none;\n      box-sizing: border-box;\n    }\n\n    .hsp-form-row select {\n      appearance: auto;\n      -webkit-appearance: menulist;\n      -moz-appearance: menulist;\n      white-space: nowrap;\n      overflow: visible;\n    }\n\n    .hsp-form-row input:focus,\n    .hsp-form-row select:focus {\n      border-color: var(--hsp-blue);\n      box-shadow: 0 0 0 3px rgba(11, 74, 143, 0.12);\n    }\n\n    .hsp-input-unit {\n      position: relative;\n    }\n\n    .hsp-input-unit input {\n      padding-right: 48px;\n    }\n\n    .hsp-input-unit span {\n      position: absolute;\n      right: 14px;\n      top: 50%;\n      transform: translateY(-50%);\n      color: var(--hsp-muted);\n      font-size: 13px;\n      font-weight: 700;\n      pointer-events: none;\n    }\n\n    .hsp-two-cols {\n      display: grid;\n      grid-template-columns: 1fr 1fr;\n      gap: 14px;\n    }\n\n    .hsp-custom-density {\n      display: none;\n    }\n\n    .hsp-helper {\n      font-size: 12px;\n      color: var(--hsp-muted);\n      margin-top: 5px;\n      line-height: 1.5;\n    }\n\n    .hsp-actions {\n      display: flex;\n      gap: 12px;\n      flex-wrap: wrap;\n      margin-top: 18px;\n    }\n\n    .hsp-btn {\n      appearance: none;\n      border: none;\n      border-radius: 999px;\n      padding: 12px 18px;\n      font-size: 14px;\n      font-weight: 800;\n      cursor: pointer;\n      text-decoration: none;\n      display: inline-flex;\n      align-items: center;\n      justify-content: center;\n      transition: transform 0.15s ease, box-shadow 0.15s ease;\n    }\n\n    .hsp-btn:hover {\n      transform: translateY(-1px);\n      box-shadow: 0 8px 18px rgba(15, 23, 42, 0.12);\n    }\n\n    .hsp-btn-primary {\n      background: var(--hsp-blue);\n      color: #fff;\n    }\n\n    .hsp-btn-secondary {\n      background: #fff;\n      color: var(--hsp-blue);\n      border: 1px solid #b8cce4;\n    }\n\n    .hsp-inline-result {\n      margin-top: 18px;\n      background: linear-gradient(135deg, #e9f8f3, #ffffff);\n      border: 1px solid #b9e5d6;\n      border-radius: 14px;\n      padding: 16px 18px;\n    }\n\n    .hsp-inline-result-label {\n      font-size: 14px;\n      font-weight: 700;\n      color: #0d5f4d;\n      margin-bottom: 8px;\n    }\n\n    .hsp-inline-result-value {\n      font-size: 36px;\n      line-height: 1;\n      font-weight: 900;\n      color: #0f7a63;\n      margin-bottom: 8px;\n      letter-spacing: -0.03em;\n    }\n\n    .hsp-inline-result-tip {\n      font-size: 13px;\n      color: #5f6b7a;\n      line-height: 1.5;\n    }\n\n    .hsp-next-step {\n      margin-top: 16px;\n      background: #fff;\n      border: 1px solid #cfe6dd;\n      border-radius: 14px;\n      padding: 16px;\n    }\n\n    .hsp-next-step strong {\n      display: block;\n      color: #0d5f4d;\n      margin-bottom: 8px;\n      font-size: 14px;\n    }\n\n    .hsp-next-step p {\n      margin: 0;\n      font-size: 13px;\n      line-height: 1.6;\n      color: var(--hsp-muted);\n    }\n\n    .hsp-mini-table {\n      margin-top: 24px;\n      overflow-x: auto;\n      border: 1px solid var(--hsp-border);\n      border-radius: 14px;\n    }\n\n    .hsp-mini-table table {\n      width: 100%;\n      border-collapse: collapse;\n      min-width: 640px;\n      background: #fff;\n    }\n\n    .hsp-mini-table th,\n    .hsp-mini-table td {\n      text-align: left;\n      padding: 12px 14px;\n      border-bottom: 1px solid #e5edf5;\n      font-size: 14px;\n    }\n\n    .hsp-mini-table th {\n      background: #f0f6ff;\n      color: #143d66;\n      font-weight: 800;\n    }\n\n    .hsp-mini-table tr:last-child td {\n      border-bottom: 0;\n    }\n\n    .hsp-disclaimer {\n      margin-top: 16px;\n      font-size: 13px;\n      color: var(--hsp-muted);\n      line-height: 1.6;\n      background: #fff8ed;\n      border: 1px solid #f4d7aa;\n      border-radius: 12px;\n      padding: 12px 14px;\n    }\n\n    @media (max-width: 820px) {\n      .hsp-panel-weight-tool {\n        padding: 20px;\n      }\n\n      .hsp-tool-grid,\n      .hsp-two-cols {\n        grid-template-columns: 1fr;\n      }\n\n      .hsp-panel-diagram {\n        min-height: 420px;\n      }\n\n      .hsp-dim-text {\n        font-size: 24px;\n      }\n\n      .hsp-dim-line,\n      .hsp-dim-tick {\n        stroke-width: 2.2;\n      }\n\n      .hsp-inline-result-value {\n        font-size: 32px;\n      }\n    }\n  <\/style>\n\n  <div class=\"hsp-tool-header\">\n    <span class=\"hsp-tool-kicker\">Strumento di ingegneria gratuito<\/span>\n    <h2>Calcolatore del peso del pannello<\/h2>\n    <p>Stimare rapidamente il peso di una porta, di una copertura, di un coperchio o di un pannello di un'apparecchiatura in base al materiale, all'altezza, alla larghezza e allo spessore. Utilizzate il risultato per calcolare la coppia di tenuta necessaria per la vostra cerniera dinamometrica.<\/p>\n  <\/div>\n\n  <div class=\"hsp-tool-grid\">\n    <div class=\"hsp-visual-card\">\n      <h3>Dimensioni della porta\/del pannello<\/h3>\n\n      <div class=\"hsp-panel-diagram\" aria-label=\"Diagramma delle dimensioni di porte e pannelli\">\n        <svg class=\"hsp-door-svg\" viewbox=\"0 0 1100 1414\" role=\"img\" aria-label=\"Diagramma altezza pannello porta larghezza spessore\">\n          <defs>\n            <lineargradient id=\"hspDoorFront\" x1=\"0\" y1=\"0\" x2=\"1\" y2=\"1\">\n              <stop offset=\"0%\" stop-color=\"#e9dfd1\"\/>\n              <stop offset=\"100%\" stop-color=\"#d8ccbc\"\/>\n            <\/lineargradient>\n            <lineargradient id=\"hspDoorSide\" x1=\"0\" y1=\"0\" x2=\"1\" y2=\"1\">\n              <stop offset=\"0%\" stop-color=\"#a59d91\"\/>\n              <stop offset=\"100%\" stop-color=\"#80786e\"\/>\n            <\/lineargradient>\n            <lineargradient id=\"hspDoorTop\" x1=\"0\" y1=\"0\" x2=\"1\" y2=\"1\">\n              <stop offset=\"0%\" stop-color=\"#cfc4b7\"\/>\n              <stop offset=\"100%\" stop-color=\"#b7ac9f\"\/>\n            <\/lineargradient>\n          <\/defs>\n\n          <!-- Closed solid door panel -->\n          <polygon class=\"hsp-door-top\" points=\"280,130 720,130 800,170 360,170\"><\/polygon>\n          <polygon class=\"hsp-door-side\" points=\"280,130 360,170 360,1140 280,1100\"><\/polygon>\n          <rect class=\"hsp-door-front\" x=\"360\" y=\"170\" width=\"440\" height=\"970\" rx=\"2\"><\/rect>\n\n          <!-- Height dimension -->\n          <line class=\"hsp-dim-line dim-height\" x1=\"870\" y1=\"150\" x2=\"870\" y2=\"1100\"><\/line>\n          <line class=\"hsp-dim-tick dim-height\" x1=\"825\" y1=\"165\" x2=\"905\" y2=\"150\"><\/line>\n          <line class=\"hsp-dim-tick dim-height\" x1=\"825\" y1=\"1115\" x2=\"905\" y2=\"1100\"><\/line>\n          <polygon class=\"hsp-arrow dim-height-arrow-top\" points=\"862,190 878,190 870,162\"><\/polygon>\n          <polygon class=\"hsp-arrow dim-height-arrow-bottom\" points=\"862,1060 878,1060 870,1088\"><\/polygon>\n          <text class=\"hsp-dim-text dim-height-text\" x=\"930\" y=\"640\">Porta<\/text>\n          <text class=\"hsp-dim-text dim-height-text\" x=\"930\" y=\"705\">Altezza<\/text>\n\n          <!-- Width dimension -->\n          <line class=\"hsp-dim-line dim-width\" x1=\"350\" y1=\"1210\" x2=\"820\" y2=\"1118\"><\/line>\n          <line class=\"hsp-dim-tick dim-width\" x1=\"310\" y1=\"1182\" x2=\"395\" y2=\"1230\"><\/line>\n          <line class=\"hsp-dim-tick dim-width\" x1=\"775\" y1=\"1092\" x2=\"855\" y2=\"1138\"><\/line>\n          <polygon class=\"hsp-arrow dim-width-arrow-left\" points=\"413,1206 436,1217 429,1191\"><\/polygon>\n          <polygon class=\"hsp-arrow dim-width-arrow-right\" points=\"758,1138 735,1127 742,1153\"><\/polygon>\n          <text class=\"hsp-dim-text dim-width-text\" x=\"585\" y=\"1265\">Larghezza della porta<\/text>\n\n          <!-- Thickness dimension -->\n          <line class=\"hsp-dim-line dim-thickness\" x1=\"205\" y1=\"1170\" x2=\"318\" y2=\"1136\"><\/line>\n          <line class=\"hsp-dim-tick dim-thickness\" x1=\"170\" y1=\"1161\" x2=\"223\" y2=\"1181\"><\/line>\n          <line class=\"hsp-dim-tick dim-thickness\" x1=\"294\" y1=\"1113\" x2=\"344\" y2=\"1145\"><\/line>\n          <polygon class=\"hsp-arrow dim-thickness-arrow-left\" points=\"238,1160 255,1176 248,1151\"><\/polygon>\n          <polygon class=\"hsp-arrow dim-thickness-arrow-right\" points=\"286,1145 269,1129 276,1154\"><\/polygon>\n          <text class=\"hsp-dim-text dim-thickness-text-1\" x=\"72\" y=\"1270\">Porta<\/text>\n          <text class=\"hsp-dim-text dim-thickness-text-2\" x=\"52\" y=\"1335\">Spessore<\/text>\n\n          <!-- Active dots -->\n          <circle class=\"active-dot active-height-dot\" cx=\"870\" cy=\"640\" r=\"0\"><\/circle>\n          <circle class=\"active-dot active-width-dot\" cx=\"585\" cy=\"1160\" r=\"0\"><\/circle>\n          <circle class=\"active-dot active-thickness-dot\" cx=\"262\" cy=\"1150\" r=\"0\"><\/circle>\n        <\/svg>\n      <\/div>\n\n      <div class=\"hsp-formula-box\">\n        <strong>Formula:<\/strong><br>\n        Peso del pannello (kg) = Densit\u00e0 \u00d7 Altezza (mm) \u00d7 Larghezza (mm) \u00d7 Spessore (mm) \u00f7 1.000.000\n      <\/div>\n    <\/div>\n\n    <div class=\"hsp-calculator-card\">\n      <h3>Calcolo del peso del pannello<\/h3>\n\n      <div class=\"hsp-form-row\">\n        <label for=\"hsp-material\">Materiale<\/label>\n        <select id=\"hsp-material\">\n          <option value=\"0.80\">MDF \/ Pannello di fibra a media densit\u00e0 - 0,80<\/option>\n          <option value=\"0.70\">Pannello di particelle - 0,70<\/option>\n          <option value=\"0.60\">Compensato - 0,60<\/option>\n          <option value=\"0.50\">Pannello alveolare - 0,50<\/option>\n          <option value=\"1.20\">Acrilico - 1,20<\/option>\n          <option value=\"2.50\">Vetro \/ Specchio - 2,50<\/option>\n          <option value=\"2.70\">Alluminio - 2,70<\/option>\n          <option value=\"7.85\">Acciaio al carbonio - 7,85<\/option>\n          <option value=\"7.93\">Acciaio inox 304 - 7,93<\/option>\n          <option value=\"8.00\">Acciaio inox 316 - 8,00<\/option>\n          <option value=\"custom\">Densit\u00e0 personalizzata<\/option>\n        <\/select>\n        <div class=\"hsp-helper\">La densit\u00e0 utilizza valori approssimativi di peso specifico. Utilizzare una densit\u00e0 personalizzata per materiali speciali o pannelli compositi.<\/div>\n      <\/div>\n\n      <div class=\"hsp-form-row hsp-custom-density\" id=\"hsp-custom-density-wrap\">\n        <label for=\"hsp-density\">Densit\u00e0\/gravit\u00e0 specifica personalizzata<\/label>\n        <input id=\"hsp-density\" type=\"number\" min=\"0\" step=\"0.01\" placeholder=\"Esempio: 7,85\">\n      <\/div>\n\n      <div class=\"hsp-two-cols\">\n        <div class=\"hsp-form-row\">\n          <label for=\"hsp-height\">Altezza del pannello<\/label>\n          <div class=\"hsp-input-unit\">\n            <input id=\"hsp-height\" type=\"number\" min=\"0\" step=\"1\" placeholder=\"Altezza\">\n            <span>mm<\/span>\n          <\/div>\n        <\/div>\n\n        <div class=\"hsp-form-row\">\n          <label for=\"hsp-width\">Larghezza del pannello<\/label>\n          <div class=\"hsp-input-unit\">\n            <input id=\"hsp-width\" type=\"number\" min=\"0\" step=\"1\" placeholder=\"Larghezza\">\n            <span>mm<\/span>\n          <\/div>\n        <\/div>\n      <\/div>\n\n      <div class=\"hsp-form-row\">\n        <label for=\"hsp-thickness\">Spessore del pannello<\/label>\n        <div class=\"hsp-input-unit\">\n          <input id=\"hsp-thickness\" type=\"number\" min=\"0\" step=\"0.1\" placeholder=\"Spessore\">\n          <span>mm<\/span>\n        <\/div>\n        <div class=\"hsp-helper\">Utilizzare lo spessore effettivo del materiale, non l'altezza o la larghezza totale della porta.<\/div>\n      <\/div>\n\n      <div class=\"hsp-actions\">\n        <button class=\"hsp-btn hsp-btn-primary\" type=\"button\" id=\"hsp-calc-btn\">Calcolo del peso<\/button>\n        <button class=\"hsp-btn hsp-btn-secondary\" type=\"button\" id=\"hsp-reset-btn\">Reset<\/button>\n      <\/div>\n\n      <div class=\"hsp-inline-result\" id=\"hsp-inline-result-box\">\n        <div class=\"hsp-inline-result-label\">Peso stimato del panel<\/div>\n        <div class=\"hsp-inline-result-value\"><span id=\"hsp-result\">0.00<\/span> kg<\/div>\n        <div class=\"hsp-inline-result-tip\">Utilizzare questo valore come input per il peso del pannello quando si calcola la forza di tenuta della cerniera di coppia richiesta.<\/div>\n      <\/div>\n\n      <div class=\"hsp-next-step\">\n        <strong>Passo successivo: calcolare la coppia di cerniere necessaria<\/strong>\n        <p>Dopo aver stimato il peso del pannello, inserirlo nel calcolatore della coppia di cerniere insieme alla distanza del centro di gravit\u00e0, al fattore di sicurezza e al numero di cerniere.<\/p>\n        <div class=\"hsp-actions\">\n          <a class=\"hsp-btn hsp-btn-primary\" href=\"https:\/\/manufactorhinge.com\/it\/torque-hinge-calculator\/\">Utilizzare il calcolatore della coppia di cerniere<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n\n  <div class=\"hsp-mini-table\">\n    <table>\n      <thead>\n        <tr>\n          <th>Materiale<\/th>\n          <th>Densit\u00e0 approssimativa \/ Peso specifico<\/th>\n          <th>Uso tipico<\/th>\n        <\/tr>\n      <\/thead>\n      <tbody>\n        <tr>\n          <td>MDF \/ Pannello di particelle \/ Compensato<\/td>\n          <td>0.60-0.80<\/td>\n          <td>Porte per mobili, coperture per interni, pannelli per impieghi leggeri<\/td>\n        <\/tr>\n        <tr>\n          <td>Acrilico \/ Vetro<\/td>\n          <td>1.20-2.50<\/td>\n          <td>Display, coperture protettive, pannelli trasparenti<\/td>\n        <\/tr>\n        <tr>\n          <td>Alluminio<\/td>\n          <td>2.70<\/td>\n          <td>Pannelli leggeri per macchine e coperture per attrezzature<\/td>\n        <\/tr>\n        <tr>\n          <td>Acciaio al carbonio<\/td>\n          <td>7.85<\/td>\n          <td>Porte industriali, coperture in acciaio, pannelli per macchinari<\/td>\n        <\/tr>\n        <tr>\n          <td>Acciaio inox 304 \/ 316<\/td>\n          <td>7.93-8.00<\/td>\n          <td>Pannelli resistenti ai lavaggi, all'esterno, alla lavorazione degli alimenti e alla corrosione<\/td>\n        <\/tr>\n      <\/tbody>\n    <\/table>\n  <\/div>\n\n  <div class=\"hsp-disclaimer\">\n    Questo calcolatore fornisce solo una stima del peso del pannello. Il peso reale pu\u00f2 variare a seconda di ritagli, nervature, maniglie, inserti in vetro, isolamento, cavi, staffe, rivestimento e altri accessori. Per la scelta della cerniera di coppia, utilizzare il peso realistico pi\u00f9 elevato dell'assemblaggio.\n  <\/div>\n\n  <script>\n    document.addEventListener('DOMContentLoaded', function () {\n      const material = document.getElementById('hsp-material');\n      const customWrap = document.getElementById('hsp-custom-density-wrap');\n      const densityInput = document.getElementById('hsp-density');\n      const heightInput = document.getElementById('hsp-height');\n      const widthInput = document.getElementById('hsp-width');\n      const thicknessInput = document.getElementById('hsp-thickness');\n      const result = document.getElementById('hsp-result');\n      const calcBtn = document.getElementById('hsp-calc-btn');\n      const resetBtn = document.getElementById('hsp-reset-btn');\n      const diagram = document.querySelector('.hsp-panel-diagram');\n\n      if (!material || !heightInput || !widthInput || !thicknessInput || !result || !calcBtn) {\n        console.error('Panel Weight Calculator: one or more required elements are missing.');\n        return;\n      }\n\n      function clearDiagramActive() {\n        if (!diagram) return;\n        diagram.classList.remove('is-height-active', 'is-width-active', 'is-thickness-active');\n      }\n\n      function setDiagramActive(type) {\n        clearDiagramActive();\n        if (!diagram) return;\n        diagram.classList.add('is-' + type + '-active');\n      }\n\n      function getDensity() {\n        if (material.value === 'custom') {\n          return parseFloat(densityInput.value) || 0;\n        }\n        return parseFloat(material.value) || 0;\n      }\n\n      function calculateWeight() {\n        const density = getDensity();\n        const height = parseFloat(heightInput.value) || 0;\n        const width = parseFloat(widthInput.value) || 0;\n        const thickness = parseFloat(thicknessInput.value) || 0;\n\n        const weight = density * height * width * thickness \/ 1000000;\n        result.textContent = weight > 0 ? weight.toFixed(2) : '0.00';\n      }\n\n      material.addEventListener('change', function () {\n        if (material.value === 'custom') {\n          if (customWrap) customWrap.style.display = 'block';\n        } else {\n          if (customWrap) customWrap.style.display = 'none';\n          if (densityInput) densityInput.value = '';\n        }\n        calculateWeight();\n      });\n\n      heightInput.addEventListener('focus', function () {\n        setDiagramActive('height');\n      });\n\n      widthInput.addEventListener('focus', function () {\n        setDiagramActive('width');\n      });\n\n      thicknessInput.addEventListener('focus', function () {\n        setDiagramActive('thickness');\n      });\n\n      heightInput.addEventListener('blur', clearDiagramActive);\n      widthInput.addEventListener('blur', clearDiagramActive);\n      thicknessInput.addEventListener('blur', clearDiagramActive);\n\n      heightInput.addEventListener('input', calculateWeight);\n      widthInput.addEventListener('input', calculateWeight);\n      thicknessInput.addEventListener('input', calculateWeight);\n\n      if (densityInput) {\n        densityInput.addEventListener('input', calculateWeight);\n      }\n\n      calcBtn.addEventListener('click', function () {\n        calculateWeight();\n      });\n\n      if (resetBtn) {\n        resetBtn.addEventListener('click', function () {\n          material.value = '0.80';\n          if (densityInput) densityInput.value = '';\n          heightInput.value = '';\n          widthInput.value = '';\n          thicknessInput.value = '';\n          if (customWrap) customWrap.style.display = 'none';\n          result.textContent = '0.00';\n          clearDiagramActive();\n        });\n      }\n\n      calculateWeight();\n    });\n  <\/script>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Free Engineering Tool Panel Weight Calculator Quickly estimate the weight of a door, cover, lid, or equipment panel by material, height, width, and thickness. Use the result to calculate the required holding torque for your torque hinge. Door \/ Panel Dimensions Door Height Door Width Door Thickness Formula: Panel Weight (kg) = Density \u00d7 Height [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"class_list":["post-3839","page","type-page","status-publish","hentry"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Panel Weight Calculator for Torque Hinge Selection<\/title>\n<meta name=\"description\" content=\"Calculate estimated panel, door, or cover weight using material density, height, width, and thickness for hinge and hardware selection.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manufactorhinge.com\/it\/panel-weight-calculator\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Panel Weight Calculator for Torque Hinge Selection\" \/>\n<meta property=\"og:description\" content=\"Calculate estimated panel, door, or cover weight using material density, height, width, and thickness for hinge and hardware selection.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manufactorhinge.com\/it\/panel-weight-calculator\/\" \/>\n<meta property=\"og:site_name\" content=\"HSP Industrial Hinges\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-23T08:39:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/manufactorhinge.com\/panel-weight-calculator\/\",\"url\":\"https:\/\/manufactorhinge.com\/panel-weight-calculator\/\",\"name\":\"Panel Weight Calculator for Torque Hinge Selection\",\"isPartOf\":{\"@id\":\"https:\/\/manufactorhinge.com\/#website\"},\"datePublished\":\"2026-05-23T07:57:31+00:00\",\"dateModified\":\"2026-05-23T08:39:58+00:00\",\"description\":\"Calculate estimated panel, door, or cover weight using material density, height, width, and thickness for hinge and hardware selection.\",\"breadcrumb\":{\"@id\":\"https:\/\/manufactorhinge.com\/panel-weight-calculator\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/manufactorhinge.com\/panel-weight-calculator\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/manufactorhinge.com\/panel-weight-calculator\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/manufactorhinge.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Panel Weight Calculator\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/manufactorhinge.com\/#website\",\"url\":\"https:\/\/manufactorhinge.com\/\",\"name\":\"Torque & Industrial Hinge Manufacturer\",\"description\":\"Torque &amp; Industrial Hinge Manufacturer\",\"publisher\":{\"@id\":\"https:\/\/manufactorhinge.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/manufactorhinge.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/manufactorhinge.com\/#organization\",\"name\":\"Torque & Industrial Hinge Manufacturer\",\"url\":\"https:\/\/manufactorhinge.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/manufactorhinge.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/manufactorhinge.com\/wp-content\/uploads\/2026\/03\/logo-1.webp\",\"contentUrl\":\"https:\/\/manufactorhinge.com\/wp-content\/uploads\/2026\/03\/logo-1.webp\",\"width\":145,\"height\":46,\"caption\":\"Torque & Industrial Hinge Manufacturer\"},\"image\":{\"@id\":\"https:\/\/manufactorhinge.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calcolatore del peso del pannello per la selezione delle cerniere a coppia","description":"Calcolare il peso stimato del pannello, dell'anta o del rivestimento in base alla densit\u00e0 del materiale, all'altezza, alla larghezza e allo spessore per la scelta delle cerniere e della ferramenta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manufactorhinge.com\/it\/panel-weight-calculator\/","og_locale":"it_IT","og_type":"article","og_title":"Panel Weight Calculator for Torque Hinge Selection","og_description":"Calculate estimated panel, door, or cover weight using material density, height, width, and thickness for hinge and hardware selection.","og_url":"https:\/\/manufactorhinge.com\/it\/panel-weight-calculator\/","og_site_name":"HSP Industrial Hinges","article_modified_time":"2026-05-23T08:39:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manufactorhinge.com\/panel-weight-calculator\/","url":"https:\/\/manufactorhinge.com\/panel-weight-calculator\/","name":"Calcolatore del peso del pannello per la selezione delle cerniere a coppia","isPartOf":{"@id":"https:\/\/manufactorhinge.com\/#website"},"datePublished":"2026-05-23T07:57:31+00:00","dateModified":"2026-05-23T08:39:58+00:00","description":"Calcolare il peso stimato del pannello, dell'anta o del rivestimento in base alla densit\u00e0 del materiale, all'altezza, alla larghezza e allo spessore per la scelta delle cerniere e della ferramenta.","breadcrumb":{"@id":"https:\/\/manufactorhinge.com\/panel-weight-calculator\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manufactorhinge.com\/panel-weight-calculator\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/manufactorhinge.com\/panel-weight-calculator\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manufactorhinge.com\/"},{"@type":"ListItem","position":2,"name":"Panel Weight Calculator"}]},{"@type":"WebSite","@id":"https:\/\/manufactorhinge.com\/#website","url":"https:\/\/manufactorhinge.com\/","name":"Produttore di cerniere industriali e di coppia","description":"Produttore di cerniere industriali e di coppia","publisher":{"@id":"https:\/\/manufactorhinge.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manufactorhinge.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/manufactorhinge.com\/#organization","name":"Produttore di cerniere industriali e di coppia","url":"https:\/\/manufactorhinge.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/manufactorhinge.com\/#\/schema\/logo\/image\/","url":"https:\/\/manufactorhinge.com\/wp-content\/uploads\/2026\/03\/logo-1.webp","contentUrl":"https:\/\/manufactorhinge.com\/wp-content\/uploads\/2026\/03\/logo-1.webp","width":145,"height":46,"caption":"Torque & Industrial Hinge Manufacturer"},"image":{"@id":"https:\/\/manufactorhinge.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/pages\/3839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/comments?post=3839"}],"version-history":[{"count":0,"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/pages\/3839\/revisions"}],"wp:attachment":[{"href":"https:\/\/manufactorhinge.com\/it\/wp-json\/wp\/v2\/media?parent=3839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}